{"id":5231,"date":"2026-03-24T12:00:00","date_gmt":"2026-03-24T11:00:00","guid":{"rendered":"https:\/\/mtvi-judo.de\/wordpress\/?p=5231"},"modified":"2026-03-26T14:13:25","modified_gmt":"2026-03-26T13:13:25","slug":"frohe-ostern-und-hajime-fuer-den-fruehling","status":"publish","type":"post","link":"https:\/\/mtvi-judo.de\/wordpress\/2026\/03\/24\/frohe-ostern-und-hajime-fuer-den-fruehling\/","title":{"rendered":"Frohe Ostern und \u201eHajime\u201c f\u00fcr den Fr\u00fchling!"},"content":{"rendered":"\n<p>Liebe Judoka, Eltern und Fans des MTV Isenb\u00fcttel,<\/p>\n\n\n\n<p>wir w\u00fcnschen euch ein frohes Osterfest! Hoffentlich nutzt ihr die Feiertage, um nach den ersten Monaten des Jahres 2026 kurz durchzuatmen und die Energiespeicher wieder aufzuladen. Hinter uns liegt bereits ein packender Start ins Jahr und vor uns wartet eine Matte voller Herausforderungen.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\"><strong>Wir blicken zur\u00fcck auf ein starkes erstes Quartal 2026<\/strong><\/h5>\n\n\n\n<p>Unsere Bundesligak\u00e4mpfer sind nach <a href=\"https:\/\/mtvi-judo.de\/wordpress\/2026\/02\/28\/besser-zusammen\/\" data-type=\"link\" data-id=\"https:\/\/mtvi-judo.de\/wordpress\/2026\/02\/28\/besser-zusammen\/\" target=\"_blank\" rel=\"noreferrer noopener\">erfolgreichem Trainingslager<\/a> in ihre jeweiligen Saisons gestartet. Besonders stolz sind wir auf die Premieren im Oberhaus; Ilias K\u00fcster startete bereits mit den Adlern Bottrop in seine Erstligasaison und konnte zwei Siege zum Heimsieg gegen Spremberg beisteuern. Amani startet nach den Osterferien mit den Schmiedegirls aus Walheim. Die &#8222;heimischen&#8220; Zweitbundesligarecken der M\u00e4nnermannschaft des Braunschweiger Judoclubs fuhren gegen die Berliner ein <a href=\"https:\/\/www.braunschweiger-jc.de\/?p=22229\" data-type=\"link\" data-id=\"https:\/\/www.braunschweiger-jc.de\/?p=22229\" target=\"_blank\" rel=\"noreferrer noopener\">9:5 Heimsieg<\/a> ein.<\/p>\n\n\n\n<p>Lia-Saphira Voigt setzte ein Ausrufezeichen und erk\u00e4mpfte sich einen hervorragenden 5. Platz bei den <a href=\"https:\/\/mtvi-judo.de\/wordpress\/2026\/03\/02\/starker-5-platz-auf-der-dem-2026-fuer-lis\/\" data-type=\"link\" data-id=\"https:\/\/mtvi-judo.de\/wordpress\/2026\/03\/02\/starker-5-platz-auf-der-dem-2026-fuer-lis\/\" target=\"_blank\" rel=\"noreferrer noopener\">Deutschen Einzelmeisterschaften der U18 in Leipzig<\/a>. Beim <a href=\"https:\/\/mtvi-judo.de\/wordpress\/2026\/03\/23\/erfolge-in-brandenburg\/\" data-type=\"link\" data-id=\"https:\/\/mtvi-judo.de\/wordpress\/2026\/03\/23\/erfolge-in-brandenburg\/\" target=\"_blank\" rel=\"noreferrer noopener\">3. Brandenburgpokal<\/a> sicherte sie sich Ende M\u00e4rz Platz 2! N\u00e4chster Halt: Bundessichtungsturnier U16 mit Trainer Christian Spilner am 18.05. in Duisburg und noch eine Schippe drauflegen. Elias Lammert reihte sich in Brandenburg in der MTV-U18-Generation \u00fcbrigens mit der Silbermedaille ein. Tomekk-Leonidas Stephani errang immerhin noch den dritten Platz nach l\u00e4ngerer Verletzungspause.<\/p>\n\n\n\n<p>Auch unsere J\u00fcngsten zeigten bei der <a href=\"https:\/\/mtvi-judo.de\/wordpress\/2026\/03\/02\/isenbuetteler-nachwuchsjudoka-erfolgreich-bei-der-bem-ret-in-northeim\/\" data-type=\"link\" data-id=\"https:\/\/mtvi-judo.de\/wordpress\/2026\/03\/02\/isenbuetteler-nachwuchsjudoka-erfolgreich-bei-der-bem-ret-in-northeim\/\" target=\"_blank\" rel=\"noreferrer noopener\">Bezirksmeisterschaft U11<\/a> und dem Regionsturnier U15 in Northeim, dass mit Isenb\u00fcttel immer zu rechnen ist. Kira Miethe und Neu-Isenb\u00fctteler Bennet Barby werden Bezirksmeister, Nora Rhode letztlich Vize. In der U15 erk\u00e4mpft sich Nikolai Kositsyn mit vier vorzeitigen Siegen Gold; Ben Blum, Tom Gl\u00f6ckner &amp; Theo M\u00f6hle holen Silber.<\/p>\n\n\n\n<p>Auch mit dem <a href=\"https:\/\/mtvi-judo.de\/wordpress\/2026\/03\/22\/silber-coup-in-der-u13-team-isenbuettel-stuermt-aufs-podest\/\" data-type=\"link\" data-id=\"https:\/\/mtvi-judo.de\/wordpress\/2026\/03\/22\/silber-coup-in-der-u13-team-isenbuettel-stuermt-aufs-podest\/\" target=\"_blank\" rel=\"noreferrer noopener\">Team U13<\/a> stand in Braunschweig bei der Bezirksmannschaftsmeisterschaft am Ende die Silbermedaille zu Buche. Nach Siegen in der Vorrunde gegen den TV Jahn Wolfsburg und Bovenden, folgte der Finaleinzug gegen den Boxclub Gifhorn. Das St\u00fctzpunktteam aus Braunschweig sicherte sich am Ende Gold; knapp dahinter die Hehlenrieder.<\/p>\n\n\n\n<p>Viele Judoka der U18 und \u00e4lter haben nach intensiver Vorbereitung im Januar ihre <a href=\"https:\/\/mtvi-judo.de\/wordpress\/2026\/03\/09\/erfolgreicher-start-in-die-guertelpruefungssaision-2026\/\" data-type=\"link\" data-id=\"https:\/\/mtvi-judo.de\/wordpress\/2026\/03\/09\/erfolgreicher-start-in-die-guertelpruefungssaision-2026\/\" target=\"_blank\" rel=\"noreferrer noopener\">neuen Graduierungen<\/a> erreicht. Die n\u00e4chste Kerbe im Ast:-)<\/p>\n\n\n\n<h5 class=\"wp-block-heading\"><strong>Ab Ostern geht es Schlag auf Schlag<\/strong><\/h5>\n\n\n\n<p>Direkt an Ostern macht sich ein voller MTV-Bus auf den Weg zum wohl gr\u00f6\u00dften internationalen Turnier Skandinaviens. Frei nach dem Motto: \u201eNeue Grenzen ausloten!\u201c geht es f\u00fcr die Isenb\u00fctteler Judoka unter der Regie von Stefan Verh\u00fclsdonk dann bei den <a href=\"https:\/\/copenhagenopen.com\/\" data-type=\"link\" data-id=\"https:\/\/copenhagenopen.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">Copenhagen Open 2026<\/a> auf Medaillenjagd.<\/p>\n\n\n\n<p>Au\u00dferdem stehen im April wichtige Kampftage der 1. und 2. Bundesliga an (u.a. in Walheim und Hamburg). Am WE 25.\/26.04. finden zudem die <a href=\"https:\/\/www.njv.de\/inside-njv\/alle-news\/newsdetail\/news\/hinweise-zur-lem-maennerfrauen-und-lmm-u13-am-26042026\/?tx_news_pi1%5Bcontroller%5D=News&amp;tx_news_pi1%5Baction%5D=detail&amp;cHash=210544354354950e274df2ffca67d1b3\" data-type=\"link\" data-id=\"https:\/\/www.njv.de\/inside-njv\/alle-news\/newsdetail\/news\/hinweise-zur-lem-maennerfrauen-und-lmm-u13-am-26042026\/?tx_news_pi1%5Bcontroller%5D=News&amp;tx_news_pi1%5Baction%5D=detail&amp;cHash=210544354354950e274df2ffca67d1b3\" target=\"_blank\" rel=\"noreferrer noopener\">Landesmannschaftsmeisterschaften (LMM) der U13 statt und die LEM M&amp;F in Georgsmarienh\u00fctte<\/a> statt.<\/p>\n\n\n\n<p>Ein absolutes Highlight findet direkt vor unserer Haust\u00fcr statt: Am 23.05. ist Isenb\u00fcttel Ausrichter der Norddeutschen Einzelmeisterschaften (NDEM) der M\u00e4nner und Frauen! Au\u00dferdem zieht es unsere Nachwuchsk\u00e4mpfer zur Bezirksmeisterschaft der U15 (30.05.).<\/p>\n\n\n\n<p>Der Juni beginnt dann mit den Deutschen Einzelmeisterschaften der M\u00e4nner\/Frauen in Duisburg (05.\u201307.06.). Am 13.06. wird Isenb\u00fcttel erneut zum Zentrum des Judosports, wenn wir die Landeseinzelmeisterschaften (LEM) der U15 ausrichten. Die Norddeutschen Meisterschaften der U15 (27.06.) sind dann der H\u00f6hepunkt der U15-Serie.<\/p>\n\n\n\n<p>Was f\u00fcr die Gro\u00dfen mit den Highlights Norddeutsche U15 und Deutsche M&amp;F enden soll, soll mit dem <a href=\"https:\/\/mtvi-judo.de\/wp-content\/uploads\/2026\/03\/Ausschreibung-25.-Fuchsturnier-2026.pdf\" data-type=\"link\" data-id=\"https:\/\/mtvi-judo.de\/wp-content\/uploads\/2026\/03\/Ausschreibung-25.-Fuchsturnier-2026.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Fuchsturnier in Cremlingen<\/a> am 19.04. und dem <a href=\"https:\/\/mtvi-judo.de\/wp-content\/uploads\/2026\/03\/Tora-Cup_Ausschreibung_2026.pdf\" data-type=\"link\" data-id=\"https:\/\/mtvi-judo.de\/wp-content\/uploads\/2026\/03\/Tora-Cup_Ausschreibung_2026.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">TORA-Cup<\/a> bei unseren Judofreunden in Nienhagen am 14.06. f\u00fcr unsere j\u00fcngsten Newcomer U8, U10 &amp; U13 der Start in den Wettkampfsport sein; viel los bis zur Sommerpause:-)<\/p>\n\n\n\n<p>Wir freuen uns darauf, euch nach Ostern wieder mit vollem Einsatz auf der Matte zu sehen! Genie\u00dft die freien Tage und bleibt sportlich.<\/p>\n\n\n\n<p>Euer Trainerteam<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Liebe Judoka, Eltern und Fans des MTV Isenb\u00fcttel, wir w\u00fcnschen euch ein frohes Osterfest! Hoffentlich nutzt ihr die Feiertage, um nach den ersten Monaten des [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":5234,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"two_page_speed":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-5231","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktuelles"],"publishpress_future_action":{"enabled":false,"date":"2028-05-13 12:47:16","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/mtvi-judo.de\/wordpress\/wp-json\/wp\/v2\/posts\/5231","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mtvi-judo.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mtvi-judo.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mtvi-judo.de\/wordpress\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/mtvi-judo.de\/wordpress\/wp-json\/wp\/v2\/comments?post=5231"}],"version-history":[{"count":20,"href":"https:\/\/mtvi-judo.de\/wordpress\/wp-json\/wp\/v2\/posts\/5231\/revisions"}],"predecessor-version":[{"id":5267,"href":"https:\/\/mtvi-judo.de\/wordpress\/wp-json\/wp\/v2\/posts\/5231\/revisions\/5267"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mtvi-judo.de\/wordpress\/wp-json\/wp\/v2\/media\/5234"}],"wp:attachment":[{"href":"https:\/\/mtvi-judo.de\/wordpress\/wp-json\/wp\/v2\/media?parent=5231"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mtvi-judo.de\/wordpress\/wp-json\/wp\/v2\/categories?post=5231"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mtvi-judo.de\/wordpress\/wp-json\/wp\/v2\/tags?post=5231"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}